{"id":25,"date":"2023-08-02T10:45:42","date_gmt":"2023-08-02T08:45:42","guid":{"rendered":"http:\/\/test.zulejka.it\/?p=25"},"modified":"2023-08-02T10:45:48","modified_gmt":"2023-08-02T08:45:48","slug":"la-funzione-meteophoto-della-app-meteotracker-documentazione-fotografica-di-condizioni-meteo-e-orografia-abbinata-ai-dati-misurati-in-quellistante","status":"publish","type":"post","link":"https:\/\/test.zulejka.it\/index.php\/2023\/08\/02\/la-funzione-meteophoto-della-app-meteotracker-documentazione-fotografica-di-condizioni-meteo-e-orografia-abbinata-ai-dati-misurati-in-quellistante\/","title":{"rendered":"La funzione \u201cMeteoPhoto\u201d della App MeteoTracker. Documentazione fotografica di condizioni meteo e orografia abbinata ai dati misurati in quell&#8217;istante"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La funzione&nbsp;<strong><em>MeteoPhoto<\/em><\/strong>, presente sulla&nbsp;<strong>App mobile MeteoTracker<\/strong>&nbsp;(<a rel=\"noreferrer noopener\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.iotopon.meteotracker\" target=\"_blank\">Android<\/a>&nbsp;e&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/apps.apple.com\/ng\/app\/meteotracker\/id1563581083\" target=\"_blank\">iOS<\/a>), consente di associare il contesto ambientale e orografico presenti al momento dell\u2019acquisizione dell\u2019immagine e i dati meteo rilevati da MeteoTracker in quel momento, con il loro inserimento nell&#8217;header (o footer) della foto, insieme a luogo, data e ora dello scatto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le foto vengono poi visualizzate sulla dashboard MeteoTracker, con un&#8217;icona posizionata su mappa esattamente nel punto in cui \u00e8 stata scattata.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/meteotracker.it\/wp-content\/uploads\/2023\/07\/63d64a476f0de707c4e19fd3-1024x653.jpg\" alt=\"\" class=\"wp-image-306\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/meteotracker.it\/wp-content\/uploads\/2023\/07\/image-3.png\" alt=\"\" class=\"wp-image-310\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per esempio, con la <strong>MeteoPhoto che riportiamo sotto<\/strong> \u00e8 stato possibile documentare visivamente la vicinanza alla base delle nuvole associando alla foto gli interessanti <strong>dati meteo rilevati a un&#8217;altitudine prossima a quella di condensazione<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/meteotracker.it\/wp-content\/uploads\/2023\/07\/image-2-1024x653.png\" alt=\"\" class=\"wp-image-308\" width=\"437\" height=\"278\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dalla&nbsp;<a rel=\"noreferrer noopener\" href=\"http:\/\/app.meteotracker.com\/\" target=\"_blank\">dashboard desktop MeteoTracker<\/a>&nbsp;\u00e8 poi possibile effettuare un\u2019analisi pi\u00f9 dettagliata e approfondita dei dati misurati, anche con l\u2019ausilio di parametri secondari calcolati dalla App, quali&nbsp;<strong>gradiente termico verticale<\/strong>&nbsp;(in termini pi\u00f9 rigorosi: la componente verticale del gradiente termico) e&nbsp;<strong><em>dew-point<\/em><\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/meteotracker.it\/wp-content\/uploads\/2023\/07\/image-5.png\" alt=\"\" class=\"wp-image-312\" width=\"377\" height=\"406\"\/><figcaption class=\"wp-element-caption\"><em>Attivazione della funzione MeteoPhoto su Android<\/em><br><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/meteotracker.it\/wp-content\/uploads\/2023\/07\/image-4.png\" alt=\"\" class=\"wp-image-311\" width=\"384\" height=\"366\"\/><figcaption class=\"wp-element-caption\"><em>Attivazione della funzione MeteoPhoto su iOS<\/em><br><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Nella <strong>dashboard desktop<\/strong> MeteoTracker \u00e8 possibile&nbsp;<strong>filtrare<\/strong>&nbsp;le sessioni che contengono MeteoPhoto utilizzando il tasto evidenziato nell\u2019immagine sotto.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/meteotracker.it\/wp-content\/uploads\/2023\/07\/image-6-1024x245.png\" alt=\"\" class=\"wp-image-314\" width=\"719\" height=\"171\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La funzione&nbsp;MeteoPhoto, presente sulla&nbsp;App mobile MeteoTracker&nbsp;(Android&nbsp;e&nbsp;iOS), consente di associare il contesto ambientale e orografico presenti al momento dell\u2019acquisizione dell\u2019immagine e i dati meteo rilevati da MeteoTracker in quel momento, con il loro inserimento nell&#8217;header (o footer) della foto, insieme a luogo, data e ora dello scatto. Le foto vengono poi visualizzate sulla dashboard MeteoTracker, con&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-25","post","type-post","status-publish","format-standard","hentry","category-blog"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/test.zulejka.it\/index.php\/wp-json\/wp\/v2\/posts\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.zulejka.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/test.zulejka.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/test.zulejka.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/test.zulejka.it\/index.php\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":1,"href":"https:\/\/test.zulejka.it\/index.php\/wp-json\/wp\/v2\/posts\/25\/revisions"}],"predecessor-version":[{"id":26,"href":"https:\/\/test.zulejka.it\/index.php\/wp-json\/wp\/v2\/posts\/25\/revisions\/26"}],"wp:attachment":[{"href":"https:\/\/test.zulejka.it\/index.php\/wp-json\/wp\/v2\/media?parent=25"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/test.zulejka.it\/index.php\/wp-json\/wp\/v2\/categories?post=25"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/test.zulejka.it\/index.php\/wp-json\/wp\/v2\/tags?post=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}